{"id":3489,"date":"2021-05-06T18:43:43","date_gmt":"2021-05-06T21:43:43","guid":{"rendered":"https:\/\/gabrieliezzi.com\/portal\/?p=3489"},"modified":"2021-05-06T18:43:43","modified_gmt":"2021-05-06T21:43:43","slug":"zabaleta-y-paula-espanol-recorrieron-el-mercado-federal-ambulante-en-hurlingham","status":"publish","type":"post","link":"https:\/\/columnajuridica.com.ar\/portal\/2021\/05\/06\/zabaleta-y-paula-espanol-recorrieron-el-mercado-federal-ambulante-en-hurlingham\/","title":{"rendered":"Zabaleta y Paula Espa\u00f1ol recorrieron el Mercado Federal Ambulante en Hurlingham"},"content":{"rendered":"<p>El intendente de Hurlingham, Juan Zabaleta, recorri\u00f3 junto a la secretaria de Comercio Interior de la Naci\u00f3n, Paula Espa\u00f1ol, el Mercado Federal Ambulante que se realiz\u00f3 en el predio del Palacio Municipal. Se trata de un programa nacional coordinado con distintos municipios del AMBA, a trav\u00e9s del cual se ofrecen bolsones con frutas y verduras provenientes del Mercado Central de Buenos Aires a precios mayoristas y accesibles.<\/p>\n<p>Zabaleta se refiri\u00f3 a la importancia de esta propuesta y declar\u00f3: \u00abEl Gobierno del presidente Fern\u00e1ndez tambi\u00e9n cuida el bolsillo de los argentinos, y mucho m\u00e1s en pandemia. Este programa nos trae frutas y verduras de estaci\u00f3n, en cantidad, con precios de entre $190 y $290. Indudablemente provoca un acceso importante a la compra para los vecinos en estos momentos tan dif\u00edciles\u00bb. Y en ese sentido, a\u00f1adi\u00f3: \u00abCuando comenzamos el ciclo escolar pusimos en marcha el Kit Escolar Social, con precios accesibles en la compra de art\u00edculos vinculados a la educaci\u00f3n, y tambi\u00e9n mantenemos la Canasta Popular en los supermercados de barrio\u00bb.<\/p>\n<p>Por su parte, Espa\u00f1ol se\u00f1al\u00f3: \u00abEsta propuesta la hacemos en conjunto con la Provincia de Buenos Aires y las y los intendentes, con quienes venimos trabajando desde el a\u00f1o pasado para dar respuesta a las necesidades de la poblaci\u00f3n y para que las pol\u00edticas del Estado Nacional lleguen realmente al territorio\u201d<\/p>\n<p>En esta primera etapa se vendieron bolsones de 5 kg con verduras pesadas y hortalizas, verduras estacionales y de hoja, y frutas. Los camiones recorrer\u00e1n distintos puntos del distrito, as\u00ed como tambi\u00e9n otros municipios, y cada semana se ir\u00e1 modificando la oferta, incorporando productos frescos como carnes, l\u00e1cteos, y otros bienes de consumo masivo y cotidiano.<\/p>\n<p>El programa fue puesto en marcha a trav\u00e9s de un convenio que firmaron los funcionarios, y la feria cont\u00f3 con una organizaci\u00f3n especial para evitar la aglomeraci\u00f3n de vecinos, y que todos puedan adquirir los productos de la forma m\u00e1s segura. Durante la recorrida estuvo presente, acompa\u00f1ando al intendente, el presidente del Honorable Concejo Deliberante, Dami\u00e1n Selci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente de Hurlingham, Juan Zabaleta, recorri\u00f3 junto a la secretaria de Comercio Interior de la Naci\u00f3n, Paula Espa\u00f1ol, el Mercado Federal Ambulante que se realiz\u00f3 en el predio del Palacio Municipal. Se trata de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3490,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts\/3489"}],"collection":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=3489"}],"version-history":[{"count":0,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts\/3489\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=3489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=3489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=3489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}