{"id":3468,"date":"2021-02-18T18:25:14","date_gmt":"2021-02-18T21:25:14","guid":{"rendered":"https:\/\/gabrieliezzi.com\/portal\/?p=3468"},"modified":"2021-02-18T18:25:14","modified_gmt":"2021-02-18T21:25:14","slug":"zabaleta-superviso-el-inicio-de-la-vacunacion-a-mayores-de-70-anos-y-a-grupos-de-riesgo","status":"publish","type":"post","link":"https:\/\/columnajuridica.com.ar\/portal\/2021\/02\/18\/zabaleta-superviso-el-inicio-de-la-vacunacion-a-mayores-de-70-anos-y-a-grupos-de-riesgo\/","title":{"rendered":"Zabaleta supervis\u00f3 el inicio de la vacunaci\u00f3n a mayores de 70 a\u00f1os y a grupos de riesgo"},"content":{"rendered":"<p><strong><em>El intendente estuvo presente en la Escuela Secundaria T\u00e9cnica N\u00ba 1 de Villa Tesei, donde se vacun\u00f3 al primer vecino. En la jornada particip\u00f3 el subdirector Ejecutivo del PAMI, Mart\u00edn Rodr\u00edguez.<\/em><\/strong><\/p>\n<p>El intendente de Hurlingham, Juan Zabaleta, junto al subdirector Ejecutivo del PAMI, Mart\u00edn Rodr\u00edguez, supervis\u00f3 el inicio de la vacunaci\u00f3n contra el Covid-19 a mayores de 70 a\u00f1os y a personas que forman parte de los denominados grupos de riesgo. Se trata de vecinos que se inscribieron a trav\u00e9s del sistema de registro voluntario \u201cBuenos Aires Vacunate\u201d, que se articula con el gobierno bonaerense. En esta instancia, los puntos de aplicaci\u00f3n se encuentran en la Escuela Secundaria T\u00e9cnica N\u00ba 1 \u201cOEA\u201d de Villa Tesei y en la Escuela Secundaria N\u00ba 9 de William Morris.<\/p>\n<p>\u201cLes dijimos a las argentinas y a los argentinos que comenz\u00e1bamos a vacunar antes de fin de a\u00f1o, as\u00ed lo hicimos a fines de diciembre en nuestro hospital al personal de salud, ahora estamos, tambi\u00e9n como el Gobernador y el Presidente se comprometieron, en la escuela t\u00e9cnica n\u00famero 1, en Villa Tesei, hay cinco mesas de vacunaci\u00f3n destinadas a vecinos que se inscribieron en la p\u00e1gina vacunatepba. La vacuna es futuro y esperanza y estamos muy contentos\u201d, manifest\u00f3 el intendente.<\/p>\n<p>Adem\u00e1s, se refiri\u00f3 al operativo de inscripci\u00f3n que se lleva adelante en el distrito: \u201cEstamos desde el fin de semana con compa\u00f1eros y trabajadores y trabajadoras municipales yendo casa por casa con un chaleco que dice \u2018Vacunate Hurlingham\u2019, tambi\u00e9n con mesas en las calles, en plazas y en centros comerciales, para que los vecinos puedan acceder a la inscripci\u00f3n y vacunarse\u201d.<\/p>\n<p>Por su parte, Mart\u00edn Rodr\u00edguez se\u00f1al\u00f3: \u201cHoy es un d\u00eda muy importante porque empieza la campa\u00f1a de vacunaci\u00f3n masiva a los adultos mayores de 70 a\u00f1os, ya ven\u00edamos vacunando desde la provincia de Buenos Aires a personal de salud y se sigui\u00f3 por las personas mayores que se encuentran en residencias de larga estad\u00eda. Estamos muy contentos porque vamos avanzando paso a paso, la vacuna es esperanza y nos devuelve la posibilidad de recuperar la vida que ten\u00edamos, la cotidianeidad, el trabajo, la escuela, los afectos, as\u00ed que estamos contentos de seguir en ese camino\u201d.<\/p>\n<p>Las personas mayores de 70 que se inscribieron voluntariamente a trav\u00e9s del sitio <a href=\"http:\/\/www.vacunatepba.gba.gob.ar\/\">www.vacunatepba.gba.gob.ar<\/a>\u00a0y que se registraron en los puntos de inscripci\u00f3n casa por casa o en las mesas que se encuentran en distintos lugares del partido, recibir\u00e1n la confirmaci\u00f3n de sus turnos para acercarse a los lugares asignados.<\/p>\n<p>En la jornada estuvieron presentes la secretaria de Salud de la comuna, Magdalena Ragatky Caffera; los presidentes del Honorable Concejo Deliberante, Dami\u00e1n Selci, y del Consejo Escolar, Jorge Ver\u00f3n; y los concejales Carolina Castro, Viviana Lodos y Fabrizio Acu\u00f1a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente estuvo presente en la Escuela Secundaria T\u00e9cnica N\u00ba 1 de Villa Tesei, donde se vacun\u00f3 al primer vecino. En la jornada particip\u00f3 el subdirector Ejecutivo del PAMI, Mart\u00edn Rodr\u00edguez. El intendente de Hurlingham,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3469,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts\/3468"}],"collection":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=3468"}],"version-history":[{"count":0,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts\/3468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=3468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=3468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=3468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}