{"id":3234,"date":"2021-03-09T15:11:25","date_gmt":"2021-03-09T18:11:25","guid":{"rendered":"https:\/\/gabrieliezzi.com\/portal\/?p=3234"},"modified":"2021-03-09T15:11:25","modified_gmt":"2021-03-09T18:11:25","slug":"fallos-penales-de-interes-general-suspension-del-juicio-a-prueba-4","status":"publish","type":"post","link":"https:\/\/columnajuridica.com.ar\/portal\/2021\/03\/09\/fallos-penales-de-interes-general-suspension-del-juicio-a-prueba-4\/","title":{"rendered":"Fallos Penales de Inter\u00e9s General: SUSPENSI\u00d3N DEL JUICIO A PRUEBA"},"content":{"rendered":"<p>\u201c-El orden p\u00fablico que signa la materia propia del derecho penal, obliga al juez siempre a analizar la validez del dictamen fiscal, incluso en aquellos supuestos donde se presta el consentimiento para la concesi\u00f3n del instituto de la suspensi\u00f3n de juicio a prueba (voto del juez D\u00edas).<\/p>\n<p>&nbsp;<\/p>\n<p>-La autoinhabilitaci\u00f3n es una soluci\u00f3n posible en materia de lesiones culposas para la concesi\u00f3n de la suspensi\u00f3n del juicio a prueba (voto del juez D\u00edas)<\/p>\n<p>Citas de \u201cCrovetto Dom\u00ednguez\u201d, Reg. 271\/2018; \u201cBonillas\u201d, Reg. 205\/2016 y \u201cPosternak\u201d, Reg. 688\/2015<\/p>\n<p><sup>\u00a0<\/sup><\/p>\n<p>-Implic\u00f3 una err\u00f3nea interpretaci\u00f3n del art. 76 bis CP la argumentaci\u00f3n del juez de grado que rechaza la solicitud de suspensi\u00f3n del juicio a prueba, en tanto no alcanza a demostrar una arbitrariedad o irracionalidad de la opini\u00f3n del fiscal que, a su turno, remarc\u00f3 que se encontraban cumplidos todos los requisitos previstos en la norma, pues el imputado no registraba antecedentes condenatorios, la pena que podr\u00eda imponerse de ser condenado ser\u00eda en suspenso, ofreci\u00f3 una reparaci\u00f3n en la medida de sus posibilidades \u2013rechazada por la denunciante- y ofreci\u00f3 autoinhabilitarse (voto del juez D\u00edas)<\/p>\n<p>&nbsp;<\/p>\n<p>-No existi\u00f3 \u201cun caso\u201d para resolver si la fiscal\u00eda coincidi\u00f3 con la defensa en que correspond\u00eda hacer lugar a la suspensi\u00f3n del juicio a prueba y ese consentimiento se sustent\u00f3 en una de las posibles interpretaciones del art. 76 bis CP (voto del juez Sarrabayrouse)<\/p>\n<p>Citas de \u201cSosa\u201d, Reg. 129\/2016 y \u201cCalandriello\u201d, Reg. 2485\/2020<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u201cFerreyra, Daniel Alberto s\/ recurso de casaci\u00f3n\u201d; CNCCC 53271\/2018, Sala 2, Reg. 171\/2021, resuelta el 24 de febrero de 2021<\/strong>\u201c<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/gabrieliezzi.com\/portal\/wp-content\/uploads\/2021\/03\/CNCCC-N\u00b0-18-53271_2018-Reg.-171_2021.pdf\">Fallo Completo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c-El orden p\u00fablico que signa la materia propia del derecho penal, obliga al juez siempre a analizar la validez del dictamen fiscal, incluso en aquellos supuestos donde se presta el consentimiento para la concesi\u00f3n del&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2988,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts\/3234"}],"collection":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=3234"}],"version-history":[{"count":0,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts\/3234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/media\/2988"}],"wp:attachment":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=3234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=3234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=3234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}