{"id":3097,"date":"2020-11-06T16:55:32","date_gmt":"2020-11-06T19:55:32","guid":{"rendered":"https:\/\/gabrieliezzi.com\/portal\/?p=3097"},"modified":"2020-11-06T16:55:32","modified_gmt":"2020-11-06T19:55:32","slug":"fallos-penales-de-interes-general-caso-1-medidas-de-prueba","status":"publish","type":"post","link":"https:\/\/columnajuridica.com.ar\/portal\/2020\/11\/06\/fallos-penales-de-interes-general-caso-1-medidas-de-prueba\/","title":{"rendered":"Fallos Penales de Inter\u00e9s General &#8211; Caso 1- Medidas de prueba"},"content":{"rendered":"<p>\u201c(\u2026) La defensa de O. D. S. recurri\u00f3 en apelaci\u00f3n la decisi\u00f3n fechada el 29 de septiembre pasado, en cuanto se dispuso la obtenci\u00f3n compulsiva de muestras biol\u00f3gicas del imputado para realizar un estudio comparativo de ADN, y fundament\u00f3 los agravios en el memorial que se incorpor\u00f3 al sistema de gesti\u00f3n Lex 100. Tambi\u00e9n se agreg\u00f3 el memorial formulado por la Fiscal\u00eda General, mediante el que peticion\u00f3 la homologaci\u00f3n de lo decidido.<br \/>\nLa asistencia t\u00e9cnica sostuvo que la medida de prueba que se pretender obtener de manera compulsiva implica una afectaci\u00f3n al derecho de defensa (art\u00edculos 14.3, inciso \u201ce\u201d del Pacto Internacional de Derechos Civiles y Pol\u00edticos y 8.2, inciso \u201cf\u201d de la Convenci\u00f3n Americana sobre Derechos Humanos) y al debido proceso.<br \/>\nEn tal sentido, aleg\u00f3 que de la decisi\u00f3n recurrida no se desprenden los motivos en los que se funda la medida ordenada, pues la mera alusi\u00f3n a su utilidad, pertinencia y razonabilidad es insuficiente.<br \/>\nAl respecto, esta Sala considera que, en el caso, la realizaci\u00f3n de un estudio como el ordenado por la jueza de la instancia anterior no importa una violaci\u00f3n de las garant\u00edas constitucionales del encausado, pues constituye una medida razonable y proporcional a la gravedad del hecho atribuido, m\u00e1xime cuando es sabido que este tipo de procedimientos, en el \u00e1mbito forense, se realizan con arreglo a las t\u00e9cnicas corrientes en la medicina, sin resultar humillantes ni degradantes, y no implican riesgos para la salud del imputado (De Luca, Javier Augusto, Pruebas sobre el cuerpo del imputado o testigos y las garant\u00edas constitucionales, en Revista de Derecho Penal, Garant\u00edas constitucionales y nulidades procesales, 2001-I, Rubinzal-Culzoni, p\u00e1g. 396 y de esta Sala, causas n\u00fameros 39.862, \u201cF., R.\u201d, del 9 de noviembre de 2010, 27.546\/16 \u201cM., G. R.\u201d, del 28 de junio de 2017 y 46.157\/2013 \u201cO., P. O.\u201d, del 30 de septiembre de 2020).<br \/>\nPor lo dem\u00e1s, de adverso a lo sostenido por el recurrente, se estima que la decisi\u00f3n cuestionada satisface los recaudos exigidos por la normativa procesal, pues la se\u00f1ora jueza de grado se ha pronunciado fundadamente acerca de la necesidad, razonabilidad y proporcionalidad de la medida que, en el caso, guarda vinculaci\u00f3n con el objeto procesal del sumario, en tanto resulta pertinente la comparaci\u00f3n con los perfiles gen\u00e9ticos obtenidos por el Cuerpo M\u00e9dico Forense a partir de las muestras biol\u00f3gicas halladas tanto en el lugar del hecho como en el cuerpo de la v\u00edctima.<br \/>\nEn consecuencia, como se encuentran cumplidos los requisitos relativos al modo en que debe ser ordenada la extracci\u00f3n de muestras biol\u00f3gicas del imputado y se evidencian satisfechos los recaudos del art\u00edculo 218 bis del C\u00f3digo Procesal Penal (\u2026)\u201d<br \/>\n<a href=\"https:\/\/gabrieliezzi.com\/portal\/wp-content\/uploads\/2020\/11\/N\u00b0-171-S-O-D-.pdf\">Fallo completo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c(\u2026) La defensa de O. D. S. recurri\u00f3 en apelaci\u00f3n la decisi\u00f3n fechada el 29 de septiembre pasado, en cuanto se dispuso la obtenci\u00f3n compulsiva de muestras biol\u00f3gicas del imputado para realizar un estudio comparativo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2988,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts\/3097"}],"collection":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/comments?post=3097"}],"version-history":[{"count":0,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/posts\/3097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/media\/2988"}],"wp:attachment":[{"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/media?parent=3097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/categories?post=3097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/columnajuridica.com.ar\/portal\/wp-json\/wp\/v2\/tags?post=3097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}